{"id":610,"date":"2021-05-04T13:19:52","date_gmt":"2021-05-04T11:19:52","guid":{"rendered":"https:\/\/blog.reformhaus-bacher.de\/?p=610"},"modified":"2021-05-18T15:25:27","modified_gmt":"2021-05-18T13:25:27","slug":"hautpeeling","status":"publish","type":"post","link":"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/","title":{"rendered":"Beautybasics und Hautpeelings einfach selbst herstellen"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Wer genau wissen will, welche Stoffe mit dem Peeling auf&nbsp;die Haut gerubbelt oder ins Badewasser gegeben werden,&nbsp;kann sich die beliebten Pflegeprodukte auch einfach&nbsp;selbst herstellen. Echte Multitalente sind dabei&nbsp;<strong>basische&nbsp;Hautpeelings<\/strong>&nbsp;aus Salzen,&nbsp;die einen&nbsp;<strong>pH-Wert<\/strong>&nbsp;von&nbsp;<strong>ca. 7,5 \u2013 8,5<\/strong>&nbsp;aufweisen. Der Blick auf die Liste der Inhaltsstoffe ist bei Pflegeprodukten&nbsp;f\u00fcr viele Menschen selbstverst\u00e4ndlich. Sie wollen genau wissen, welche nat\u00fcrlichen oder chemischen Mittel enthalten sind.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Auch die Zahl derer, die ihre Pflege selbst zubereiten, steigt.&nbsp;Sie k\u00f6nnen so allein entscheiden, welche Stoffe in ihr&nbsp;Hautpeeling&nbsp;oder&nbsp;ihren&nbsp;Gesichtsmasken&nbsp;landen. Zudem lassen sich so Geld, \u00fcberfl\u00fcssige Verpackungen und lange Transportwege sparen. Beim&nbsp;Anr\u00fchren eigener Pflegeprodukte sind&nbsp;<strong>K\u00f6rperpflegesalze&nbsp;<\/strong>mit einem&nbsp;<strong>basischen&nbsp;pH-Wert<\/strong>&nbsp;besonders&nbsp;<strong>vielseitig&nbsp;<\/strong>in der Anwendung.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Wohltuender Badezusatz mit dem extra&nbsp;Hautpeeling-Feeling&nbsp;<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Besonders Personen mit trockener Haut kann ein basischer&nbsp;Badezusatz&nbsp;mit&nbsp;neutralem&nbsp;pH-Wert&nbsp;guttun, denn dieser ist nicht nur&nbsp;<strong>besonders sanft&nbsp;<\/strong>zur Haut, sondern regt auch die nat\u00fcrliche&nbsp;<strong>Selbst-Fettung&nbsp;<\/strong>und&nbsp;<strong>Selbstregulierung&nbsp;<\/strong>der Haut an. Spannungen und Irritationen&nbsp;auf der Haut werden so beruhigt und nach dem Bad wird eincremen oft \u00fcberfl\u00fcssig.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"220\" src=\"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/peeling-2.jpg\" alt=\"Hautpeeling Badesalz\" class=\"wp-image-618\" srcset=\"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/peeling-2.jpg 360w, https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/peeling-2-300x183.jpg 300w, https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/peeling-2-210x128.jpg 210w, https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/peeling-2-120x73.jpg 120w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Als basischer&nbsp;<strong>Badezusatz&nbsp;<\/strong>kann sowohl&nbsp;<strong>Natron<\/strong>,&nbsp;wie auch&nbsp;<strong>Salz&nbsp;<\/strong>verwendet werden. Allerdings muss&nbsp;hierbei f\u00fcr ein optimales Ergebnis der pH-Wert des Wassers&nbsp;nachgemessen werden. Denn nur bei einem Wert von circa 8,5&nbsp;bewirkt das Bad, dass der K\u00f6rper \u00fcbersch\u00fcssige S\u00e4uren an das&nbsp;Badewasser abgibt. Alternativ kann basisches K\u00f6rperpflegesalz, wie etwa von&nbsp;<strong>P.&nbsp;Jentschura\u00ae<\/strong>, verwendet werden, das den&nbsp;optimalen pH-Wert gew\u00e4hrleistet.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Zus\u00e4tzlich kann das Salz, wenn es sich noch nicht vollst\u00e4ndig in der Badewanne aufgel\u00f6st hat, als Hautpeeling verwendet werden.&nbsp;F\u00fcr den besonderen Wohlf\u00fchlfaktor werden zur Salz- bzw. Natronbasis ein paar&nbsp;<strong>Tropfen&nbsp;nat\u00fcrlicher&nbsp;\u00d6le&nbsp;<\/strong>gegeben. Entspannend wirken z. B.&nbsp;f\u00fcnf&nbsp;Tropfen&nbsp;<strong>Lavendel\u00f6l&nbsp;<\/strong>im Badewasser. F\u00fcr ein anregendes Bad kann Meersalz mit etwas Rosmarin\u00f6l, das die Durchblutung anregt, oder&nbsp;mit&nbsp;erfrischendem Zitronen\u00f6l vermischt werden.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Sanftes&nbsp;Hautpeeling&nbsp;<\/h2>\n\n\n\n<p>Ein&nbsp;Hautpeeling&nbsp;mit&nbsp;basischem pH-Wert&nbsp;hilft, abgestorbene Hautschuppen abzutragen und unterst\u00fctzt die Haut beim Erneuerungsprozess. F\u00fcr&nbsp;ein optimales Ergebnis empfehlen wir, ein Peeling&nbsp;<strong>ein- bis<\/strong>&nbsp;<strong>maximal zweimal pro Woche<\/strong>&nbsp;aufzutragen. Dieses zuvor frisch&nbsp;zuzubereiten geht schnell, ist einfach und ben\u00f6tigt nur wenige&nbsp;Zutaten. Verwenden Sie als Basis Basenpulver. F\u00fcr&nbsp;ein<strong>&nbsp;feuchtigkeitsspendendes&nbsp;Hautpeeling<\/strong>&nbsp;1 EL Basenpulver mit&nbsp;2 EL Aloe Vera und einem TL Honig vermengen. Nehmen Sie f\u00fcr den&nbsp;<strong>Frische-Kick<\/strong> etwa 1 EL Oliven\u00f6l und eine halbe&nbsp;Avocado als Zusatz. F\u00fcr die ideale Wirkung des&nbsp;Hautpeelings&nbsp;empfiehlt es sich, die Poren zuvor mit einem warmen Bad oder&nbsp;einer Dusche zu \u00f6ffnen.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pflegende&nbsp;Peeling-Maske<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Wer der Haut etwas besonders Gutes tun m\u00f6chte, setzt&nbsp;zus\u00e4tzlich und regelm\u00e4\u00dfig auf pflegende&nbsp;Peeling-Masken. Sie werden&nbsp;meist im Gesicht angewendet, k\u00f6nnen aber auch&nbsp;im Dekolletee oder an Schultern und&nbsp;Oberarmen f\u00fcr&nbsp;<strong>strahlende Haut&nbsp;<\/strong>sorgen. Auch&nbsp;<strong>basische&nbsp;Peeling-Masken<\/strong>&nbsp;k\u00f6nnen ganz einfach und&nbsp;mit wenigen Zutaten selbst anger\u00fchrt werden. <strong>Bei trockener&nbsp;Haut<\/strong>&nbsp;2 EL Basenpulver mit 1TL Oliven\u00f6l oder 1 TL Honig und 2 EL Aloe Vera&nbsp;Gel vermengen. <strong>Bei unreiner Hau<\/strong>t eignet sich Basenpulver&nbsp;mit Mineralerde als Basis, dazu 2 EL Brennnessel- oder auch&nbsp;Kamillentee und einen Spritzer Zitronensaft.&nbsp;Die basische Peeling-Maske sollte 20 \u2013 30 Minuten auf der<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p> zuvor gereinigten,&nbsp;sauberen Haut wirken k\u00f6nnen. Anschlie\u00dfend sollten erstmal&nbsp;keine Pflegeprodukte auf die Haut aufgetragen werden.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"220\" src=\"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-maske-1.jpg\" alt=\"Hautpeeling Maske\" class=\"wp-image-1023\" srcset=\"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-maske-1.jpg 360w, https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-maske-1-300x183.jpg 300w, https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-maske-1-210x128.jpg 210w, https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-maske-1-120x73.jpg 120w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Nat\u00fcrliches Deo mit basischem pH-Wert&nbsp;<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Durch&nbsp;seinen basischen pH-Wert entzieht Pflegesalz geruchsbildenden Bakterien den N\u00e4hrboden \u2013 und das ganz ohne&nbsp;k\u00fcnstliche Duftstoffe oder Aluminium. Als Alternative zu klassischen Deos kann also einfach etwas in&nbsp;<strong>Wasser gel\u00f6stes basisches Salz<\/strong>&nbsp;auf die zuvor mit Seife gewaschenen Achseln aufgetragen&nbsp;werden, dann nur noch trocknen lassen und fertig.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Wer&nbsp;sich zus\u00e4tzlich&nbsp;einen angenehmen Duft w\u00fcnscht, kann auch&nbsp;mit Pflegesalz, Wasser und einem&nbsp;beliebigen&nbsp;<strong>\u00e4therischen Bio-\u00d6l<\/strong>&nbsp;nach Wahl&nbsp;ein Deo zaubern. Dazu einfach 2 TL Natron&nbsp;mit 100 ml abgekochtem Wasser und z. B. 10 Tropfen Lavendel\u00f6l in&nbsp;eine Spr\u00fchflasche oder einen leeren Deoroller geben.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unterst\u00fctzen Sie die S\u00e4ure-Basen-Regulation der Haut mit selbst gemachten Hautpeelings.<\/p>\n","protected":false},"author":2,"featured_media":1226,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[25,5],"tags":[160,162,159,80,161,158,79],"class_list":["post-610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entspannung","category-gesundheit","tag-beautybasics","tag-deo","tag-diy","tag-hautpeeling","tag-maske","tag-peeling","tag-ph-wert","infinite-scroll-item","masonry-post","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Simple DIY Beautybasics &amp; Hautpeelings \u2013\u202fReformhaus Bacher<\/title>\n<meta name=\"description\" content=\"Unterst\u00fctzen Sie die S\u00e4ure-Basen-Regulation der Haut mit selbst gemachten Hautpeelings. Hier geht&#039;s zu DIY Hautpeelings &amp; mehr: schnell\u2713 basisch\u2713 pflegend\u2713\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Simple DIY Beautybasics &amp; Hautpeelings \u2013\u202fReformhaus Bacher\" \/>\n<meta property=\"og:description\" content=\"Unterst\u00fctzen Sie die S\u00e4ure-Basen-Regulation der Haut mit selbst gemachten Hautpeelings. Hier geht&#039;s zu DIY Hautpeelings &amp; mehr: schnell\u2713 basisch\u2713 pflegend\u2713\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/\" \/>\n<meta property=\"og:site_name\" content=\"Reformhaus Bacher\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-04T11:19:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-18T13:25:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-reformhaus-bacher-blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Caroline\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Caroline\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/\"},\"author\":{\"name\":\"Caroline\",\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/#\/schema\/person\/b0a4c00adf718687b920b6c0c0e09085\"},\"headline\":\"Beautybasics und Hautpeelings einfach selbst herstellen\",\"datePublished\":\"2021-05-04T11:19:52+00:00\",\"dateModified\":\"2021-05-18T13:25:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/\"},\"wordCount\":782,\"publisher\":{\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-reformhaus-bacher-blog.jpg\",\"keywords\":[\"beautybasics\",\"Deo\",\"diy\",\"hautpeeling\",\"Maske\",\"peeling\",\"ph wert\"],\"articleSection\":[\"Entspannung\",\"Gesundheit\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/\",\"url\":\"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/\",\"name\":\"Simple DIY Beautybasics & Hautpeelings \u2013\u202fReformhaus Bacher\",\"isPartOf\":{\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-reformhaus-bacher-blog.jpg\",\"datePublished\":\"2021-05-04T11:19:52+00:00\",\"dateModified\":\"2021-05-18T13:25:27+00:00\",\"description\":\"Unterst\u00fctzen Sie die S\u00e4ure-Basen-Regulation der Haut mit selbst gemachten Hautpeelings. Hier geht's zu DIY Hautpeelings & mehr: schnell\u2713 basisch\u2713 pflegend\u2713\",\"breadcrumb\":{\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/#primaryimage\",\"url\":\"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-reformhaus-bacher-blog.jpg\",\"contentUrl\":\"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-reformhaus-bacher-blog.jpg\",\"width\":1200,\"height\":750,\"caption\":\"sonyachny\/stock.adobe.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/reformhaus-bacher.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beautybasics und Hautpeelings einfach selbst herstellen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/#website\",\"url\":\"https:\/\/reformhaus-bacher.de\/blog\/\",\"name\":\"Reformhaus Bacher\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reformhaus-bacher.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/#organization\",\"name\":\"Reformhaus Bacher GmbH &. Co. KG\",\"url\":\"https:\/\/reformhaus-bacher.de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/03\/Reformhaus-Bacher.png\",\"contentUrl\":\"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/03\/Reformhaus-Bacher.png\",\"width\":3287,\"height\":456,\"caption\":\"Reformhaus Bacher GmbH &. Co. KG\"},\"image\":{\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/reformhaus-bacher.de\/blog\/#\/schema\/person\/b0a4c00adf718687b920b6c0c0e09085\",\"name\":\"Caroline\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Simple DIY Beautybasics & Hautpeelings \u2013\u202fReformhaus Bacher","description":"Unterst\u00fctzen Sie die S\u00e4ure-Basen-Regulation der Haut mit selbst gemachten Hautpeelings. Hier geht's zu DIY Hautpeelings & mehr: schnell\u2713 basisch\u2713 pflegend\u2713","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/","og_locale":"de_DE","og_type":"article","og_title":"Simple DIY Beautybasics & Hautpeelings \u2013\u202fReformhaus Bacher","og_description":"Unterst\u00fctzen Sie die S\u00e4ure-Basen-Regulation der Haut mit selbst gemachten Hautpeelings. Hier geht's zu DIY Hautpeelings & mehr: schnell\u2713 basisch\u2713 pflegend\u2713","og_url":"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/","og_site_name":"Reformhaus Bacher","article_published_time":"2021-05-04T11:19:52+00:00","article_modified_time":"2021-05-18T13:25:27+00:00","og_image":[{"width":1200,"height":750,"url":"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-reformhaus-bacher-blog.jpg","type":"image\/jpeg"}],"author":"Caroline","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Caroline","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/#article","isPartOf":{"@id":"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/"},"author":{"name":"Caroline","@id":"https:\/\/reformhaus-bacher.de\/blog\/#\/schema\/person\/b0a4c00adf718687b920b6c0c0e09085"},"headline":"Beautybasics und Hautpeelings einfach selbst herstellen","datePublished":"2021-05-04T11:19:52+00:00","dateModified":"2021-05-18T13:25:27+00:00","mainEntityOfPage":{"@id":"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/"},"wordCount":782,"publisher":{"@id":"https:\/\/reformhaus-bacher.de\/blog\/#organization"},"image":{"@id":"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/#primaryimage"},"thumbnailUrl":"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-reformhaus-bacher-blog.jpg","keywords":["beautybasics","Deo","diy","hautpeeling","Maske","peeling","ph wert"],"articleSection":["Entspannung","Gesundheit"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/","url":"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/","name":"Simple DIY Beautybasics & Hautpeelings \u2013\u202fReformhaus Bacher","isPartOf":{"@id":"https:\/\/reformhaus-bacher.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/#primaryimage"},"image":{"@id":"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/#primaryimage"},"thumbnailUrl":"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-reformhaus-bacher-blog.jpg","datePublished":"2021-05-04T11:19:52+00:00","dateModified":"2021-05-18T13:25:27+00:00","description":"Unterst\u00fctzen Sie die S\u00e4ure-Basen-Regulation der Haut mit selbst gemachten Hautpeelings. Hier geht's zu DIY Hautpeelings & mehr: schnell\u2713 basisch\u2713 pflegend\u2713","breadcrumb":{"@id":"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/#primaryimage","url":"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-reformhaus-bacher-blog.jpg","contentUrl":"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/05\/hautpeeling-reformhaus-bacher-blog.jpg","width":1200,"height":750,"caption":"sonyachny\/stock.adobe.com"},{"@type":"BreadcrumbList","@id":"https:\/\/reformhaus-bacher.de\/blog\/gesundheit\/entspannung\/hautpeeling\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/reformhaus-bacher.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Beautybasics und Hautpeelings einfach selbst herstellen"}]},{"@type":"WebSite","@id":"https:\/\/reformhaus-bacher.de\/blog\/#website","url":"https:\/\/reformhaus-bacher.de\/blog\/","name":"Reformhaus Bacher","description":"","publisher":{"@id":"https:\/\/reformhaus-bacher.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reformhaus-bacher.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/reformhaus-bacher.de\/blog\/#organization","name":"Reformhaus Bacher GmbH &. Co. KG","url":"https:\/\/reformhaus-bacher.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/reformhaus-bacher.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/03\/Reformhaus-Bacher.png","contentUrl":"https:\/\/reformhaus-bacher.de\/blog\/wp-content\/uploads\/2021\/03\/Reformhaus-Bacher.png","width":3287,"height":456,"caption":"Reformhaus Bacher GmbH &. Co. KG"},"image":{"@id":"https:\/\/reformhaus-bacher.de\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/reformhaus-bacher.de\/blog\/#\/schema\/person\/b0a4c00adf718687b920b6c0c0e09085","name":"Caroline"}]}},"_links":{"self":[{"href":"https:\/\/reformhaus-bacher.de\/blog\/wp-json\/wp\/v2\/posts\/610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reformhaus-bacher.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reformhaus-bacher.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reformhaus-bacher.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reformhaus-bacher.de\/blog\/wp-json\/wp\/v2\/comments?post=610"}],"version-history":[{"count":12,"href":"https:\/\/reformhaus-bacher.de\/blog\/wp-json\/wp\/v2\/posts\/610\/revisions"}],"predecessor-version":[{"id":1227,"href":"https:\/\/reformhaus-bacher.de\/blog\/wp-json\/wp\/v2\/posts\/610\/revisions\/1227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reformhaus-bacher.de\/blog\/wp-json\/wp\/v2\/media\/1226"}],"wp:attachment":[{"href":"https:\/\/reformhaus-bacher.de\/blog\/wp-json\/wp\/v2\/media?parent=610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reformhaus-bacher.de\/blog\/wp-json\/wp\/v2\/categories?post=610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reformhaus-bacher.de\/blog\/wp-json\/wp\/v2\/tags?post=610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}